{"id":58869,"date":"2026-01-13T17:54:45","date_gmt":"2026-01-13T16:54:45","guid":{"rendered":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch\/"},"modified":"2026-01-13T17:53:44","modified_gmt":"2026-01-13T16:53:44","slug":"volkswagen-amarok-dc-aventura-deutsch-58869","status":"publish","type":"vehicule","link":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/","title":{"rendered":"Volkswagen &#8211; Amarok &#8211; DC Aventura (Deutsch)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-58869","vehicule","type-vehicule","status-publish","hentry"],"acf":{"chassis":"","reference":"","version":"","titre":"","titre_premium":"","kilometrage":"","garantie_duree":false,"garantie_constructeur":false,"garantie_constructeur_debut":null,"garantie_constructeur_fin":null,"kilometrage_limite":"","type_vehicule":null,"emplacement":null,"twinner_reload_modele":false,"parking":"","numero_cle":"","nombre_de_cles":"","disponibilite":1,"disponibilite_date":null,"disponibilite_endeans":false,"categorie":false,"proprietaires_precedents":false,"date_premiere_immatriculation":null,"kit_winter_pneus":false,"carnet_entretien":true,"filtre_particule":true,"couleur_metallisee":false,"couleur_exterieur":false,"couleur_exterieur_constructeur":"","couleur_interieur":false,"equipement_interieur":false,"commentaires_publication":null,"soh_pdf":null,"soh_image":null,"soh_value":"","mobbizz_tco_1":"","mobbizz_tco_2":"","mobbizz_tco_3":"","mobbizz_atn":"","mobbizz_deductibility":"","vehicules_identiques":null,"parent_vehicle":null,"children_vehicles":null,"kia_config":null,"kia_packs":null,"kia_color":null,"import_kia_data":false,"equipment_packs":null,"twinner_reload_equipments":false,"show_equipment_text":false,"equipment_text_fr":"","equipment_text_de":"","equipment_text_en":"","equipment_text_nl":"","equipements":null,"rapport_dexpertise":null,"dammages_fr":null,"dammages_de":null,"dammages_en":null,"ignore_missing_photos":false,"photos_travail":null,"photos_twinner":null,"twinner_threesixty":"","photomotion_threesixty":"","date_vente":null,"705_digital":false,"documents_arrived_date":null,"lancer_requete_car_pass":false,"car_pass_url":"","car_pass_filename":"","car_pass_status":"","car_pass_error":"","car_pass_error_type":"","car_pass_historique_fr":null,"car_pass_historique_de":null,"car_pass_historique_nl":null,"car_pass_historique_en":null,"car_pass_submit_date":null,"erwin_reload_equipments":false,"erwin_last_control_date":null,"config_be":null,"erwin_fr":null,"erwin_de":null,"erwin_nl":null,"mobbizz_show_on_website_electric_vehicle":false,"mobbizz_show_on_website_vehicle_leasing":false,"mobbizz_update_prices":false,"mobbizz_prices_file":null,"mobbizz_cover_image":null,"mobbizz_rental_rates":null,"vehicle_on_order":false,"vehicle_on_order_version":null,"vehicle_on_order_standard_equipments_relation":null,"vehicle_on_order_optional_equipment_relation":null,"vehicle_on_order_available_colors":null,"vehicle_on_order_options":null,"vehicle_on_order_packs":null,"statut":false,"statut_ireach":"","order_tracking":false,"vehicule_lts":false,"conducteur":"","email_conducteur":"","plaque_immatriculation":"","date_dernier_kilometrage":null,"vehicule_controle":false,"premium":false,"livrable_24h":false,"vehicule_ireach":false,"saved_vehicle":true,"prix_catalogue":0,"prix_vente":0,"tva_recuperable":false,"prix_marchand":0,"prix_vehicule_base":0,"origine":false,"proprietaire_vehicule":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volkswagen - Amarok - DC Aventura (Deutsch) - Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"product.item\" \/>\n<meta property=\"og:title\" content=\"Volkswagen &#8211; Amarok &#8211; DC Aventura (Deutsch) Aventura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/\" \/>\n<meta property=\"og:site_name\" content=\"Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/\",\"url\":\"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/\",\"name\":\"Volkswagen - Amarok - DC Aventura (Deutsch) - Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich\",\"isPartOf\":{\"@id\":\"https:\/\/www.caralliance.be\/de\/#website\"},\"datePublished\":\"2026-01-13T16:54:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.caralliance.be\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00e9hicules\",\"item\":\"https:\/\/www.caralliance.be\/de\/vehicule\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Volkswagen &#8211; Amarok &#8211; DC Aventura (Deutsch)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.caralliance.be\/de\/#website\",\"url\":\"https:\/\/www.caralliance.be\/de\/\",\"name\":\"Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich\",\"description\":\"Finden Sie jetzt Ihr Traumauto!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.caralliance.be\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volkswagen - Amarok - DC Aventura (Deutsch) - Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/","og_locale":"de_DE","og_type":"product.item","og_title":"Volkswagen &#8211; Amarok &#8211; DC Aventura (Deutsch) Aventura","og_url":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/","og_site_name":"Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/","url":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/","name":"Volkswagen - Amarok - DC Aventura (Deutsch) - Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich","isPartOf":{"@id":"https:\/\/www.caralliance.be\/de\/#website"},"datePublished":"2026-01-13T16:54:45+00:00","breadcrumb":{"@id":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.caralliance.be\/de\/vehicule\/volkswagen-amarok-dc-aventura-deutsch-58869\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caralliance.be\/de\/"},{"@type":"ListItem","position":2,"name":"V\u00e9hicules","item":"https:\/\/www.caralliance.be\/de\/vehicule\/"},{"@type":"ListItem","position":3,"name":"Volkswagen &#8211; Amarok &#8211; DC Aventura (Deutsch)"}]},{"@type":"WebSite","@id":"https:\/\/www.caralliance.be\/de\/#website","url":"https:\/\/www.caralliance.be\/de\/","name":"Caralliance - Der gr\u00f6\u00dfte Bestand an Neu- und Gebrauchtfahrzeugen in der Provinz L\u00fcttich","description":"Finden Sie jetzt Ihr Traumauto!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caralliance.be\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/vehicule\/58869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/vehicule"}],"about":[{"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/types\/vehicule"}],"author":[{"embeddable":true,"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/comments?post=58869"}],"version-history":[{"count":1,"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/vehicule\/58869\/revisions"}],"predecessor-version":[{"id":58871,"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/vehicule\/58869\/revisions\/58871"}],"wp:attachment":[{"href":"https:\/\/www.caralliance.be\/de\/wp-json\/wp\/v2\/media?parent=58869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}